{"id":668,"date":"2017-10-26T13:17:13","date_gmt":"2017-10-26T15:17:13","guid":{"rendered":"http:\/\/kkturismo.com.br\/novo\/?page_id=668"},"modified":"2026-05-15T00:56:00","modified_gmt":"2026-05-15T03:56:00","slug":"praia-do-forte","status":"publish","type":"page","link":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/","title":{"rendered":"PRAIA DO FORTE"},"content":{"rendered":"<p><strong>PRAIA DO FORTE-BA<\/strong><\/p>\n<p>A\u00a0<b>Praia do Forte<\/b>\u00a0\u00e9 uma\u00a0praia\u00a0situada no\u00a0distrito\u00a0hom\u00f4nimo, no\u00a0munic\u00edpio\u00a0de\u00a0Mata de S\u00e3o Jo\u00e3o, no\u00a0estado\u00a0da\u00a0Bahia, no\u00a0Brasil. Dista cerca de 80 quil\u00f4metros da capital do estado,\u00a0Salvador. Chega-se at\u00e9 a praia pela\u00a0Estrada do Coco, uma estrada bem conservada saindo de Salvador (nas imedia\u00e7\u00f5es do\u00a0Aeroporto Internacional) e que segue at\u00e9 a divisa com o estado de\u00a0Sergipe\u00a0(nesse trecho chama-se\u00a0Linha Verde).<\/p>\n<p><strong>Transfer <\/strong><em><strong>&gt;&gt;&gt;\u00a0 carro\u00a0 com at\u00e9 (veja),valor reduzido para pagamento de ida e volta confira abaixo.<\/strong><\/em><\/p>\n<p><strong> Aeroporto x Praia do Forte\u00a0 \/\u00a0 Praia do Forte x Aeroporto<\/strong><\/p>\n<p><em><strong>1 at\u00e9 3\u00a0 pessoas\u00a0 R$ 300,00, fechando\u00a0 ida e volta R$ 550,00.<\/strong><\/em><\/p>\n<p><em><strong>4 R$ 350, 5 e 6\u00a0 pessoas\u00a0 R$ 400,00, fechando\u00a0 ida e volta R$ 750,00.\u00a0<\/strong><\/em><\/p>\n<p><em><strong>7 at\u00e9 9\u00a0 pessoas\u00a0 R$ 500,00, fechando\u00a0 ida e volta R$ 950,00.<\/strong><\/em><\/p>\n<p><em><strong>\u00a010 at\u00e9 12\u00a0 pessoas\u00a0 R$ 600,00, fechando\u00a0 ida e volta R$ 1.100,00.<\/strong><\/em><\/p>\n<p><em><strong> 13 at\u00e9 16\u00a0 pessoas\u00a0 R$ 750,00, fechando\u00a0 ida e volta R$ 1.400,00.<\/strong><\/em><\/p>\n<p><em><strong>\u00a0 Acima de 17 pessoas, contate-nos e negocie o seu transfer.<\/strong><\/em><\/p>\n<p>contato@kkturismo.com.br<\/p>\n<p>https:\/\/wa.me\/5571999613747<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Reserva e Pagamento:<\/strong><\/span><\/p>\n<p><strong>20% transfer\u00eancia ou dep\u00f3sito em conta,<\/strong><br \/>\n<strong>40% na chegada e 40% na sa\u00edda.<\/strong><\/p>\n<p><strong>Banco do Brasil:<\/strong><br \/>\n<strong>Ag.3921-7 Cc.20890-6<\/strong><\/p>\n<p><strong>Santrauedes Viagens e Turismo<\/strong><br \/>\n<strong>CNPJ.12467878000110<\/strong><\/p>\n<p><strong>Prezado (a) Para maior agilidade na reserva do servi\u00e7o(s) solicitado, por gentileza enviar comprovante de pagamento ,nome de todos os passageiros com sobrenomes, datas da chegada e de retorno com hora e n\u00fameros de v\u00f4os para a emiss\u00e3o do Voucher, agradecemos desde j\u00e1, essas informa\u00e7\u00f5es s\u00e3o de import\u00e2ncia para agendamento do servi\u00e7os e emiss\u00e3o do voucher.<\/strong><\/p>\n<p><strong>Ficaremos no aguardo para proporcionar-lhes um excelente atendimento.<\/strong><\/p>\n<p><strong>Atenciosamente: Viviane\u00a0 Santos<\/strong><\/p>\n<p><span style=\"color: #0000ff;\">https:\/\/wa.me\/5571999613747<\/span><\/p>\n<p>Em 1970, o descendente de alem\u00e3es Klaus Peters junto com um amigo arremataram 30 mil hectares de mata, coqueiros, rios e praias. A \u00e1rea inclu\u00eda tamb\u00e9m uma vila de pescadores (depois doado \u00e0 municipalidade) e um edif\u00edcio em ru\u00ednas, datado de 1551: o\u00a0Castelo Garcia D \u00c1vila, origem do nome &#8220;Praia do Forte&#8221;, posto \u00e0 venda pela fam\u00edlia baiana Padilha de Souza com o objetivo de criar um destino tur\u00edstico.<sup id=\"cite_ref-Exame_2-0\" class=\"reference\">[2]<\/sup>\u00a0A partir de 1980 tornou-se o \u00fanico dono da \u00e1rea. Depois vieram os primeiros empreendimentos: uma pousada e hotel.<sup id=\"cite_ref-Exame_2-1\" class=\"reference\">[2]<\/sup>\u00a0Em 2013 a prefeitura de Mata de S\u00e3o Jo\u00e3o inaugurou o Parque Municipal Klaus Peters, em homenagem ao empres\u00e1rio<\/p>\n<div class=\"frm_forms  with_frm_style frm_style_formidable-style\" id=\"frm_form_2_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form \" id=\"form_contact-form\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_hidden\">Contato para KKTurismo<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"2\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_2\" id=\"frm_hide_fields_2\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_2\" name=\"frm_submit_entry_2\" value=\"a77bfcfd0c\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/novo\/wp-json\/wp\/v2\/pages\/668\" \/><div id=\"frm_field_8_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_first frm_half\">\r\n    <label for=\"field_qh4icy2\" class=\"frm_primary_label\">Nome:\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_qh4icy2\" name=\"item_meta[8]\" value=\"\"  data-reqmsg=\"Nome: cannot be blank.\" aria-required=\"true\" data-invmsg=\"Nome: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_10_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_29yf4d2\" class=\"frm_primary_label\">Email:\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"email\" id=\"field_29yf4d2\" name=\"item_meta[10]\" value=\"\"  data-reqmsg=\"Email: cannot be blank.\" aria-required=\"true\" data-invmsg=\"Please enter a valid email address\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_12_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_e6lis62\" class=\"frm_primary_label\">Telefone:\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_e6lis62\" name=\"item_meta[12]\" value=\"\"  data-reqmsg=\"Telefone: cannot be blank.\" aria-required=\"true\" data-invmsg=\"Telefone: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_15_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_fol1f\" class=\"frm_primary_label\">Quantidade de Pessoas\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_fol1f\" name=\"item_meta[15]\" value=\"\"  data-invmsg=\"Quantidade de Pessoas \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_16_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_rl5pm\" class=\"frm_primary_label\">Data da Chegada:\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_rl5pm\" name=\"item_meta[16]\" value=\"00\/00\/0000\"  data-frmval=\"00\/00\/0000\" data-invmsg=\"Data da Chegada: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_17_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_qvwhy\" class=\"frm_primary_label\">Data da Saida:\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    <input type=\"text\" id=\"field_qvwhy\" name=\"item_meta[17]\" value=\"00\/00\/0000\"  data-frmval=\"00\/00\/0000\" data-invmsg=\"Data da Saida: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  \/>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_18_container\" class=\"frm_form_field form-field  frm_top_container\">\r\n    <label for=\"field_eibhq\" class=\"frm_primary_label\">Selecione o Ve\u00edculo:\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \t\t<select name=\"item_meta[18]\" id=\"field_eibhq\"  data-frmval=\"Vans\" data-invmsg=\"Selecione o Ve\u00edculo: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  >\n\t\t<option  value=\"Master\">Master<\/option><option  value=\"Sprinter\">Sprinter<\/option><option  value=\"Doblo\">Doblo<\/option><option  value=\"Spin\">Spin<\/option><option  value=\"Micro \u00d4nibus\">Micro \u00d4nibus<\/option><option  value=\"Vans\" selected='selected'>Vans<\/option>\t<\/select>\n\t\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_13_container\" class=\"frm_form_field form-field  frm_required_field frm_top_container frm_full\">\r\n    <label for=\"field_9jv0r12\" class=\"frm_primary_label\">D\u00favidas ou Mensagem:\r\n        <span class=\"frm_required\">*<\/span>\r\n    <\/label>\r\n    <textarea name=\"item_meta[13]\" id=\"field_9jv0r12\" rows=\"5\"  data-reqmsg=\"D\u00favidas ou Mensagem: cannot be blank.\" aria-required=\"true\" data-invmsg=\"D\u00favidas ou Mensagem: \u00e9 inv\u00e1lido\" aria-invalid=\"false\"  ><\/textarea>\r\n    \r\n    \r\n<\/div>\n<div id=\"frm_field_14_container\" class=\"frm_form_field form-field  frm_none_container\">\r\n    <label for=\"g-recaptcha-response\" class=\"frm_primary_label\">Captcha\r\n        <span class=\"frm_required\"><\/span>\r\n    <\/label>\r\n    \r\n    \r\n    \r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t<div class=\"frm_submit\">\r\n\r\n<button class=\"frm_button_submit\" type=\"submit\"  >Enviar<\/button>\r\n\r\n<\/div><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>PRAIA DO FORTE-BA A\u00a0Praia do Forte\u00a0\u00e9 uma\u00a0praia\u00a0situada no\u00a0distrito\u00a0hom\u00f4nimo, no\u00a0munic\u00edpio\u00a0de\u00a0Mata de S\u00e3o Jo\u00e3o, no\u00a0estado\u00a0da\u00a0Bahia, no\u00a0Brasil. Dista cerca de 80 quil\u00f4metros da capital do estado,\u00a0Salvador. Chega-se at\u00e9 a praia pela\u00a0Estrada do Coco, uma estrada bem conservada saindo de Salvador (nas imedia\u00e7\u00f5es do\u00a0Aeroporto Internacional) e que segue at\u00e9 a divisa com o estado de\u00a0Sergipe\u00a0(nesse trecho chama-se\u00a0Linha Verde). Transfer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-668","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transfer Praia do Forte kkturismo (71) 99961-3747<\/title>\n<meta name=\"description\" content=\"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transfer Praia do Forte kkturismo (71) 99961-3747\" \/>\n<meta property=\"og:description\" content=\"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/\" \/>\n<meta property=\"og:site_name\" content=\"KKTurismo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T03:56:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/\",\"url\":\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/\",\"name\":\"Transfer Praia do Forte kkturismo (71) 99961-3747\",\"isPartOf\":{\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#website\"},\"datePublished\":\"2017-10-26T15:17:13+00:00\",\"dateModified\":\"2026-05-15T03:56:00+00:00\",\"description\":\"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.\",\"breadcrumb\":{\"@id\":\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/kkturismo.com.br\/novo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRAIA DO FORTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#website\",\"url\":\"https:\/\/kkturismo.com.br\/novo\/\",\"name\":\"KKTurismo\",\"description\":\"TRANSFER\",\"publisher\":{\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kkturismo.com.br\/novo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#organization\",\"name\":\"Kktur Viagens e Turismo\",\"url\":\"https:\/\/kkturismo.com.br\/novo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kkturismo.com.br\/novo\/wp-content\/uploads\/2017\/12\/logo2.png\",\"contentUrl\":\"https:\/\/kkturismo.com.br\/novo\/wp-content\/uploads\/2017\/12\/logo2.png\",\"width\":250,\"height\":150,\"caption\":\"Kktur Viagens e Turismo\"},\"image\":{\"@id\":\"https:\/\/kkturismo.com.br\/novo\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transfer Praia do Forte kkturismo (71) 99961-3747","description":"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/","og_locale":"pt_BR","og_type":"article","og_title":"Transfer Praia do Forte kkturismo (71) 99961-3747","og_description":"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.","og_url":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/","og_site_name":"KKTurismo","article_modified_time":"2026-05-15T03:56:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/","url":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/","name":"Transfer Praia do Forte kkturismo (71) 99961-3747","isPartOf":{"@id":"https:\/\/kkturismo.com.br\/novo\/#website"},"datePublished":"2017-10-26T15:17:13+00:00","dateModified":"2026-05-15T03:56:00+00:00","description":"Temos Vans, Minivans e Sedans p\/ seu transfer apartir de R$270,00 o trecho p\/ at\u00e9 3 pessoas e R$ 500,00 ida e volta. Consulte-nos e agende o seu.","breadcrumb":{"@id":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kkturismo.com.br\/novo\/praia-do-forte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/kkturismo.com.br\/novo\/"},{"@type":"ListItem","position":2,"name":"PRAIA DO FORTE"}]},{"@type":"WebSite","@id":"https:\/\/kkturismo.com.br\/novo\/#website","url":"https:\/\/kkturismo.com.br\/novo\/","name":"KKTurismo","description":"TRANSFER","publisher":{"@id":"https:\/\/kkturismo.com.br\/novo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kkturismo.com.br\/novo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/kkturismo.com.br\/novo\/#organization","name":"Kktur Viagens e Turismo","url":"https:\/\/kkturismo.com.br\/novo\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/kkturismo.com.br\/novo\/#\/schema\/logo\/image\/","url":"https:\/\/kkturismo.com.br\/novo\/wp-content\/uploads\/2017\/12\/logo2.png","contentUrl":"https:\/\/kkturismo.com.br\/novo\/wp-content\/uploads\/2017\/12\/logo2.png","width":250,"height":150,"caption":"Kktur Viagens e Turismo"},"image":{"@id":"https:\/\/kkturismo.com.br\/novo\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/pages\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":27,"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/pages\/668\/revisions"}],"predecessor-version":[{"id":1524,"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/pages\/668\/revisions\/1524"}],"wp:attachment":[{"href":"https:\/\/kkturismo.com.br\/novo\/wp-json\/wp\/v2\/media?parent=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}